{"id":138,"count":55,"description":"","link":"https:\/\/www.gotokyo.org\/book\/th\/genre\/experience\/","name":"\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c, \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21","slug":"experience","taxonomy":"genre","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gotokyo.org\/book\/wp-json\/wp\/v2\/genre\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gotokyo.org\/book\/wp-json\/wp\/v2\/genre"}],"about":[{"href":"https:\/\/www.gotokyo.org\/book\/wp-json\/wp\/v2\/taxonomies\/genre"}],"wp:post_type":[{"href":"https:\/\/www.gotokyo.org\/book\/wp-json\/wp\/v2\/list?genre=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}